
{"id":25576889,"date":"2026-04-13T19:49:40","date_gmt":"2026-04-13T17:49:40","guid":{"rendered":"https:\/\/www.infobetting.com\/blog\/?p=25576889"},"modified":"2026-04-14T10:10:02","modified_gmt":"2026-04-14T08:10:02","slug":"pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026","status":"publish","type":"post","link":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/","title":{"rendered":"Pronostico e quote Pedro Martinez &#8211; Lorenzo Sonego, Barcellona 14-04-2026"},"content":{"rendered":"<p><strong>Pedro Martinez<\/strong> e <strong>Lorenzo Sonego<\/strong> apriranno il programma sul campo intitolato ad Andres Gimeno alle 11 del mattino. Il tennista torinese torna a giocare una partita ufficiale dopo quasi tre mesi nei quali ha dovuto curarsi per un problema al polso dunque non potr\u00e0 essere al meglio ma \u00e8 difficile dire quanto al di sotto del suo standard. Lo spagnolo invece si \u00e8 qualificato passando due turni non semplici <a href=\"https:\/\/www.infobetting.com\/tennis\/quote\/barcelona\/pedro-martinez_pablo-carreno\/12\/dett-t-46-2-q-83-782042-12.htm\">contro Pablo Carre\u00f1o<\/a>, che si \u00e8 ritirato quando era sotto 6-3 4-3, e un Marco Trungelliti in forma nel periodo. E&#8217; ben rodato sulla superficie avendo iniziato la stagione sulla terra battuta a <a href=\"https:\/\/www.infobetting.com\/tennis\/calendari\/buenos-aires\/cal-t-326-2-c-50.htm\">Buenos Aires<\/a> dove ha raggiunto i quarti di finale.<\/p>\n<h2 style=\"text-align: center\">Quote vincente Pedro Martinez &#8211; Lorenzo Sonego<\/h2>\n<table id=\"wp-tennis782471\" width=\"100%\">\n<tbody>\n<tr>\n<td style=\"width: 34%;text-align: center;color: #008e54;background-color: #b9f8b9\"><\/td>\n<td style=\"width: 33%;text-align: center;color: #008e54;background-color: #b9f8b9\"><strong>1<\/strong><\/td>\n<td style=\"width: 33%;text-align: center;color: #008e54;background-color: #b9f8b9\"><strong>2<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 34%;text-align: center;color: #000000;background-color: #ffffff\"><a target=\"_new\" href=\"https:\/\/www.admiralbet.it\/gmg\/refer\/671a7237003a14a63a954ce4\" rel=\"noopener nofollow\" target=\"_blank\">AdmiralBet<\/a><\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">1.50<\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">2.50<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 34%;text-align: center;color: #000000;background-color: #ffffff\"><a target=\"_new\" href=\"https:\/\/ntrfr.leovegas.com\/redirect.aspx?pid=3767600&amp;bid=13309\" rel=\"noopener nofollow\" target=\"_blank\">LeoVegas<\/a><\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">1.50<\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">2.60<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 34%;text-align: center;color: #000000;background-color: #ffffff\"><a target=\"_new\" href=\"https:\/\/www.starvegas.it\/gmg\/refer\/69c1719f27562f00014980c4\" rel=\"noopener nofollow\" target=\"_blank\">Starvegas<\/a><\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">1.50<\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">2.50<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 34%;text-align: center;color: #000000;background-color: #ffffff\"><a target=\"_new\" href=\"https:\/\/media.lottomaticapartners.it\/redirect.aspx?pid=6658&amp;bid=1508\" rel=\"noopener nofollow\" target=\"_blank\">Lottomatica<\/a><\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">1.50<\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">2.55<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 34%;text-align: center;color: #000000;background-color: #ffffff\"><a target=\"_new\" href=\"https:\/\/informatoriads.snai.it\/redirect.aspx?pid=9732&amp;bid=1953\" rel=\"noopener nofollow\" target=\"_blank\">Snai<\/a><\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">1.53<\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">2.50<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 34%;text-align: center;color: #000000;background-color: #ffffff\"><a target=\"_new\" href=\"https:\/\/netbetit.livepartners.com\/click.php?z=186192\" rel=\"noopener nofollow\" target=\"_blank\">Netbet.it<\/a><\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">1.50<\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">2.50<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 34%;text-align: center;color: #000000;background-color: #ffffff\"><a target=\"_new\" href=\"https:\/\/mmwebhandler.aff-online.com\/C\/42359?sr=1654290\" rel=\"noopener nofollow\" target=\"_blank\">888Sport.it<\/a><\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">1.50<\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">2.55<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 34%;text-align: center;color: #000000;background-color: #ffffff\"><a target=\"_new\" href=\"https:\/\/www.bet365.it\/hub\/it-it\/open-account-offer?affiliate=365_025276\" rel=\"noopener nofollow\" target=\"_blank\">Bet365.it<\/a><\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">1.50<\/td>\n<td style=\"width: 33%;text-align: center;color: #000000;background-color: #ffffff\">2.50<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\" style=\"width: 100%;text-align: center;color: #000000;background-color: #ffffff\">I valori pubblicati si riferiscono <b>alle 10:10 del 14\/04\/2026<\/b> e sono soggetti a variazione<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"border: solid 1px #aaa;padding: 0.8em\"><i>Questo sito confronta le quote dei bookmaker da noi selezionati, in possesso di regolare concessione ad operare in Italia rilasciata dall&#8217;Agenzia delle Dogane e dei Monopoli. Il servizio, come indicato dall&#8217;Autorit\u00e0 per le garanzie nelle comunicazioni al punto 5.6 delle proprie Linee Guida (allegate alla delibera 132\/19\/CONS), \u00e8 effettuato nel rispetto del principio di continenza, non ingannevolezza e trasparenza e non costituisce pertanto una forma di pubblicit\u00e0. E&#8217; altres\u00ec possibile che, per motivi di ordine tecnico, alcuni dei bookmaker selezionati non siano temporaneamente visibili nelle tabelle comparative.<\/i><\/div>\n<div id=\"comparazione_bonus_tabella\"><\/div>\n<h2 style=\"text-align: center\">Ultimi precedenti<\/h2>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td style=\"width: 28%;text-align: center;color: #008e54;background-color: #b9f8b9\"><strong>Torneo<\/strong><\/td>\n<td style=\"width: 15%;text-align: center;color: #008e54;background-color: #b9f8b9\"><strong>Data<\/strong><\/td>\n<td style=\"width: 28%;text-align: center;color: #008e54;background-color: #b9f8b9\"><strong>Vincitore<\/strong><\/td>\n<td style=\"width: 29%;text-align: center;color: #008e54;background-color: #b9f8b9\"><strong>Punteggio<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 28%;text-align: center;color: #000000;background-color: #ffffff\">Monte Carlo<\/td>\n<td style=\"width: 15%;text-align: center;color: #000000;background-color: #ffffff\">08-04-2025<\/td>\n<td style=\"width: 28%;text-align: center;color: #000000;background-color: #ffffff\">Pedro Martinez<\/td>\n<td style=\"width: 29%;text-align: center;color: #000000;background-color: #ffffff\">4-6 6-1 2-6<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Un solo precedente vinto dal classe 1997 di Alzira nel 2025 al Country Club. Allora partiva sfavorito mentre oggi \u00e8 lui l&#8217;uomo da battere.<\/p>\n<h2 style=\"text-align: center\">Pronostico Pedro Martinez &#8211; Lorenzo Sonego<\/h2>\n<p>I due si conoscono molto bene avendo anche vinto in doppio il torneo di Kitzb\u00fchel nel 2022. Se Sonego fosse gi\u00e0 al meglio potrebbe tranquillamente vincere ma non sarebbe comunque scontato visto che nel 2025 ha perso contro Martinez senza avere tutti questi problemi. <strong>Saremmo stupiti di un ritorno vincente del torinese<\/strong> che a quasi 31 anni dovrebbe avere bisogno di un po&#8217; di tempo per tornare competitivo ma ovviamente non si pu\u00f2 escludere.<\/p>\n<table id=\"wp-prono-tennis\" width=\"100%\">\n<tbody>\n<tr>\n<td style=\"width: 100%;text-align: left;color: #000000;background-color: #ffffff\"><b>TESTA A TESTA &#8211;&gt; 1<\/b> <b><a href=\"https:\/\/ntrfr.leovegas.com\/redirect.aspx?pid=3767600&amp;bid=13309\" target=\"_blank\" rel=\"nofollow\">LeoVegas<\/a> 1.63<\/b> <b><a href=\"https:\/\/mmwebhandler.aff-online.com\/C\/42359?sr=1654290\" target=\"_blank\" rel=\"nofollow\">888Sport.it<\/a> 1.62<\/b> <b><a href=\"https:\/\/www.starvegas.it\/gmg\/refer\/69c1719f27562f00014980c4\" target=\"_blank\" rel=\"nofollow\">Starvegas<\/a> 1.60<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><i>Quote e pronostico del 13\/04\/2026 alle ore 19:32.<\/i> <\/p>\n<div style=\"border: solid 1px #aaa;padding: 0.8em\"><i>Questo sito fornisce periodicamente pronostici, suggerimenti ed anteprime su alcune delle principali competizioni sportive. I nostri consigli aiutano i lettori a scegliere tra le offerte dei bookmaker in possesso di regolare concessione ad operare in Italia rilasciata dall&#8217;Agenzia delle Dogane e dei Monopoli. Nonostante gli sforzi nel produrre informazioni il pi\u00f9 precise possibile questa attivit\u00e0 comunque non garantisce il conseguimento di alcuna vincita. <\/i><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pedro Martinez e Lorenzo Sonego apriranno il programma sul campo intitolato ad Andres Gimeno alle 11 del mattino. Il tennista torinese torna a giocare una partita ufficiale dopo quasi tre mesi nei quali ha dovuto curarsi per un problema al polso dunque non potr\u00e0 essere al meglio ma \u00e8 difficile dire quanto al di sotto [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":25576890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[72,2,11],"tags":[1596,87],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego con quote, scontri diretti (1-0) e statistiche\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego\" \/>\n<meta property=\"og:description\" content=\"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego con quote, scontri diretti (1-0) e statistiche\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"InfoBetting\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T17:49:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T08:10:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2026\/04\/Pronostico-e-quote-Pedro-Martinez-Lorenzo-Sonego-Barcellona-14-04-2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"348\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@infobetting\" \/>\n<meta name=\"twitter:site\" content=\"@infobetting\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.infobetting.com\/blog\/#organization\",\"name\":\"Infobetting\",\"url\":\"https:\/\/www.infobetting.com\/blog\/\",\"sameAs\":[\"https:\/\/twitter.com\/infobetting\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.infobetting.com\/blog\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2016\/09\/logo-infobetting.png\",\"contentUrl\":\"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2016\/09\/logo-infobetting.png\",\"width\":209,\"height\":44,\"caption\":\"Infobetting\"},\"image\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.infobetting.com\/blog\/#website\",\"url\":\"https:\/\/www.infobetting.com\/blog\/\",\"name\":\"InfoBetting\",\"description\":\"Notizie Sportive e Pronostici Scommesse\",\"publisher\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.infobetting.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2026\/04\/Pronostico-e-quote-Pedro-Martinez-Lorenzo-Sonego-Barcellona-14-04-2026.jpg\",\"contentUrl\":\"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2026\/04\/Pronostico-e-quote-Pedro-Martinez-Lorenzo-Sonego-Barcellona-14-04-2026.jpg\",\"width\":348,\"height\":256,\"caption\":\"Pronostico e quote Pedro Martinez - Lorenzo Sonego, Barcellona 14-04-2026\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#webpage\",\"url\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/\",\"name\":\"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego\",\"isPartOf\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#primaryimage\"},\"datePublished\":\"2026-04-13T17:49:40+00:00\",\"dateModified\":\"2026-04-14T08:10:02+00:00\",\"description\":\"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego con quote, scontri diretti (1-0) e statistiche\",\"breadcrumb\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.infobetting.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tennis\",\"item\":\"https:\/\/www.infobetting.com\/blog\/cat\/tennis\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ATP\",\"item\":\"https:\/\/www.infobetting.com\/blog\/cat\/tennis\/atp\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pronostico e quote Pedro Martinez &#8211; Lorenzo Sonego, Barcellona 14-04-2026\"}]},{\"@type\":[\"Article\",\"NewsArticle\"],\"@id\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/#\/schema\/person\/0763eabf9a0c685dc4aa9aaaf0017335\"},\"headline\":\"Pronostico e quote Pedro Martinez &#8211; Lorenzo Sonego, Barcellona 14-04-2026\",\"datePublished\":\"2026-04-13T17:49:40+00:00\",\"dateModified\":\"2026-04-14T08:10:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#webpage\"},\"wordCount\":428,\"publisher\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2026\/04\/Pronostico-e-quote-Pedro-Martinez-Lorenzo-Sonego-Barcellona-14-04-2026.jpg\",\"keywords\":[\"Lorenzo Sonego\",\"Scommesse\"],\"articleSection\":[\"ATP\",\"Primo piano\",\"Tennis\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.infobetting.com\/blog\/#\/schema\/person\/0763eabf9a0c685dc4aa9aaaf0017335\",\"name\":\"Redazione\",\"description\":\"La redazione del blog e i contributi esterni.\",\"url\":\"https:\/\/www.infobetting.com\/blog\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"description":"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego con quote, scontri diretti (1-0) e statistiche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/","og_locale":"it_IT","og_type":"article","og_title":"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego","og_description":"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego con quote, scontri diretti (1-0) e statistiche","og_url":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/","og_site_name":"InfoBetting","article_published_time":"2026-04-13T17:49:40+00:00","article_modified_time":"2026-04-14T08:10:02+00:00","og_image":[{"width":348,"height":256,"url":"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2026\/04\/Pronostico-e-quote-Pedro-Martinez-Lorenzo-Sonego-Barcellona-14-04-2026.jpg","path":"\/var\/www\/html\/world.infobetting.com\/htdocs\/blog\/wp-content\/uploads\/2026\/04\/Pronostico-e-quote-Pedro-Martinez-Lorenzo-Sonego-Barcellona-14-04-2026.jpg","size":"full","id":25576890,"alt":"Pronostico e quote Pedro Martinez - Lorenzo Sonego, Barcellona 14-04-2026","pixels":89088,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@infobetting","twitter_site":"@infobetting","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.infobetting.com\/blog\/#organization","name":"Infobetting","url":"https:\/\/www.infobetting.com\/blog\/","sameAs":["https:\/\/twitter.com\/infobetting"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.infobetting.com\/blog\/#logo","inLanguage":"it-IT","url":"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2016\/09\/logo-infobetting.png","contentUrl":"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2016\/09\/logo-infobetting.png","width":209,"height":44,"caption":"Infobetting"},"image":{"@id":"https:\/\/www.infobetting.com\/blog\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.infobetting.com\/blog\/#website","url":"https:\/\/www.infobetting.com\/blog\/","name":"InfoBetting","description":"Notizie Sportive e Pronostici Scommesse","publisher":{"@id":"https:\/\/www.infobetting.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.infobetting.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2026\/04\/Pronostico-e-quote-Pedro-Martinez-Lorenzo-Sonego-Barcellona-14-04-2026.jpg","contentUrl":"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2026\/04\/Pronostico-e-quote-Pedro-Martinez-Lorenzo-Sonego-Barcellona-14-04-2026.jpg","width":348,"height":256,"caption":"Pronostico e quote Pedro Martinez - Lorenzo Sonego, Barcellona 14-04-2026"},{"@type":"WebPage","@id":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#webpage","url":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/","name":"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego","isPartOf":{"@id":"https:\/\/www.infobetting.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#primaryimage"},"datePublished":"2026-04-13T17:49:40+00:00","dateModified":"2026-04-14T08:10:02+00:00","description":"Barcellona 2026: pronostico Pedro Martinez - Lorenzo Sonego con quote, scontri diretti (1-0) e statistiche","breadcrumb":{"@id":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.infobetting.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Tennis","item":"https:\/\/www.infobetting.com\/blog\/cat\/tennis\/"},{"@type":"ListItem","position":3,"name":"ATP","item":"https:\/\/www.infobetting.com\/blog\/cat\/tennis\/atp\/"},{"@type":"ListItem","position":4,"name":"Pronostico e quote Pedro Martinez &#8211; Lorenzo Sonego, Barcellona 14-04-2026"}]},{"@type":["Article","NewsArticle"],"@id":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#article","isPartOf":{"@id":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#webpage"},"author":{"@id":"https:\/\/www.infobetting.com\/blog\/#\/schema\/person\/0763eabf9a0c685dc4aa9aaaf0017335"},"headline":"Pronostico e quote Pedro Martinez &#8211; Lorenzo Sonego, Barcellona 14-04-2026","datePublished":"2026-04-13T17:49:40+00:00","dateModified":"2026-04-14T08:10:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#webpage"},"wordCount":428,"publisher":{"@id":"https:\/\/www.infobetting.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.infobetting.com\/blog\/pronostico-e-quote-pedro-martinez-lorenzo-sonego-barcellona-14-04-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.infobetting.com\/blog\/wp-content\/uploads\/2026\/04\/Pronostico-e-quote-Pedro-Martinez-Lorenzo-Sonego-Barcellona-14-04-2026.jpg","keywords":["Lorenzo Sonego","Scommesse"],"articleSection":["ATP","Primo piano","Tennis"],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.infobetting.com\/blog\/#\/schema\/person\/0763eabf9a0c685dc4aa9aaaf0017335","name":"Redazione","description":"La redazione del blog e i contributi esterni.","url":"https:\/\/www.infobetting.com\/blog\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/posts\/25576889"}],"collection":[{"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/comments?post=25576889"}],"version-history":[{"count":0,"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/posts\/25576889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/media\/25576890"}],"wp:attachment":[{"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/media?parent=25576889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/categories?post=25576889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infobetting.com\/blog\/wp-json\/wp\/v2\/tags?post=25576889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}